{"id":2901,"date":"2016-12-11T14:31:29","date_gmt":"2016-12-11T12:31:29","guid":{"rendered":"http:\/\/www.cantabriarallye.net\/newcantabriarallye\/?p=2901"},"modified":"2016-12-11T15:32:34","modified_gmt":"2016-12-11T13:32:34","slug":"buena-actuacion-de-los-pilotos-cantabros-en-bakio","status":"publish","type":"post","link":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/buena-actuacion-de-los-pilotos-cantabros-en-bakio\/","title":{"rendered":"Buena actuaci\u00f3n de los pilotos C\u00e1ntabros en Bakio"},"content":{"rendered":"<p>Con motivo del Motor Show de Bakio, varios equipos C\u00e1ntabros se desplazaban a tierras vascas, consiguiendo unas estupendas clasificaciones dentro de los veh\u00edculos carrozados. Por una parte ten\u00edamos a Roberto L\u00f3pez Cagigal, campeonisimo de Cantabria con varios campeonatos en su poder, que con su afinado Peugeot 205 consegu\u00eda colocarse l\u00edder entre los carrozados.<br \/>\nPor otra parte, \u00abPepo\u00bb Jos\u00e9 A. Garc\u00eda Abascal era el segundo clasificado con su habitual Opel Tigra. No hay dos sin tres y la tercera posici\u00f3n era para Manuel Rodr\u00edguez \u00abLolin\u00bb, que consegu\u00eda la tercera posici\u00f3n en carrozados con su BMW, adem\u00e1s de conseguir liderar la categor\u00eda de tracci\u00f3n trasera.<br \/>\nTambien teniamos a otro Cantabro entre los Kart Cross, siendo este Javier Arco Llaguno, consiguiendo una sexta posicion en la General.<\/p>\n<table border=\"0\" align=\"center\">\n<tbody>\n<tr>\n<td>\n<div align=\"center\"><img decoding=\"async\" src=\"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-content\/uploads\/2016\/noticias\/varios\/bakio.jpg\" alt=\"\"><\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\"><span style=\"font-size: small;\">Foto: Prensa <\/span><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><!--more--> Otro nuevo \u00e9xito para los equipos C\u00e1ntabros, que adem\u00e1s de ser espectaculares, consiguen excelentes cronos.<\/p>\n<table border=\"0\" align=\"center\">\n<tbody>\n<tr>\n<td>\n<div align=\"center\"><img decoding=\"async\" src=\"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-content\/uploads\/2016\/noticias\/varios\/bakio2.jpg\" alt=\"\"><\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\"><span style=\"font-size: small;\">Foto: Prensa <\/span><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<div align=\"center\"><script src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- script_google_rectangular_336X280 --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 336px; height: 280px;\" data-ad-client=\"ca-pub-8210995772042445\" data-ad-slot=\"5950103458\"><\/ins><script>\/\/ <![CDATA[\n(adsbygoogle = window.adsbygoogle || []).push({});\n\/\/ ]]><\/script><\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Con motivo del Motor Show de Bakio, varios equipos C\u00e1ntabros se desplazaban a tierras vascas, consiguiendo unas estupendas clasificaciones dentro de los veh\u00edculos carrozados. Por una parte ten\u00edamos a Roberto L\u00f3pez Cagigal, campeonisimo de Cantabria con varios campeonatos en su poder, que con su afinado Peugeot 205 consegu\u00eda colocarse l\u00edder entre los carrozados. Por otra [&hellip;]<!-- AddThis Advanced Settings generic via filter on wp_trim_excerpt --><!-- AddThis Share Buttons generic via filter on wp_trim_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-2901","post","type-post","status-publish","format-standard","hentry","category-c3-slalom"],"_links":{"self":[{"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/posts\/2901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/comments?post=2901"}],"version-history":[{"count":2,"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/posts\/2901\/revisions"}],"predecessor-version":[{"id":2904,"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/posts\/2901\/revisions\/2904"}],"wp:attachment":[{"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/media?parent=2901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/categories?post=2901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/tags?post=2901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}