{"id":390,"date":"2014-08-25T06:07:53","date_gmt":"2014-08-25T06:07:53","guid":{"rendered":"http:\/\/www.cantabriarallye.net\/2015\/doblete-de-hyundai-en-alemania\/"},"modified":"2015-02-22T14:06:45","modified_gmt":"2015-02-22T14:06:45","slug":"doblete-de-hyundai-en-alemania","status":"publish","type":"post","link":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/doblete-de-hyundai-en-alemania\/","title":{"rendered":"Doblete de Hyundai en Alemania"},"content":{"rendered":"<p>Neuville consegu\u00eda en Alemania su primera victoria en el Campeonato del Mundo de Rallyes, tres d\u00edas despu\u00e9s de casi destruir su coche cuando dio seis vueltas de campana en el Shakedown.En la \u00faltima jornada, Neuville ha pasado de la tercera a la primera posici\u00f3n despu\u00e9s de los abandonos cuando eran l\u00edderes de Jari-Matti Latvala y Kris Meeke. Dani Sordo ha completado el doblete de Hyundai.<br \/>\nLa victoria en esta novena cita de la temporada ha sido tambi\u00e9n la primera de Hyundai en su a\u00f1o de debut en el certamen. Dani Sordo ha conseguido la segunda posici\u00f3n, completado un resultado de ensue\u00f1o para la marca coreana.<br \/>\nHace un a\u00f1o, Neuville estuvo muy cerca de la victoria en Alemania, pero fue Sordo quien finalmente se impuso. En aquella ocasi\u00f3n, el espa\u00f1ol releg\u00f3 al belga a la segunda plaza despu\u00e9s de que Neuville perdiese toda opci\u00f3n a pocos kil\u00f3metros de meta tras salirse.<\/p>\n<table border=\"0\" align=\"center\">\n<tbody>\n<tr>\n<td>\n<div align=\"center\"><img decoding=\"async\" src=\"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-content\/uploads\/2014\/pruebasmundial\/alemania\/foto.jpg\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\"><span style=\"font-family: Verdana,Arial,Helvetica,sans-serif;\">Foto:.Fonso Gonz\u00e1lez (CASAR)<\/span><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><!--more--> La historia de Neuville en el Rallye de Alemania arranc\u00f3 muy mal el jueves por la ma\u00f1ana, cuando dio seis vueltas de campana en el Shakedown. Sus mec\u00e1nicos estuvieron trabajando durante 18 horas para reconstruir su i20 WRC y Neuville les ha devuelto este esfuerzo con el mejor resultado posible, convirti\u00e9ndose en el segundo belga que gana una prueba del WRC, el primer fue Fran\u00e7ois Duval en 2005.<\/p>\n<p>\u00abCreo que hemos hecho un trabajo incre\u00edble durante los tres d\u00edas de Rallye y solo puedo dar las gracias a nuestro equipo\u00bb, ha dicho el belga. \u00abHicieron un trabajo fant\u00e1stico despu\u00e9s de nuestro accidente en el Shakedown y no pod\u00eda imaginar que lograr\u00edamos un buen resultado. Pero hemos presionado al resto de rivales y nos ha salido bien\u00bb.<\/p>\n<p>Latvala, que buscaba su primer triunfo sobre asfalto para reavivar la pelea por el t\u00edtulo, ten\u00eda casi un minuto de ventaja cuando ha arrancado la jornada, que ha constado de cuatro tramos entre los vi\u00f1edos del r\u00edo Mosel.<\/p>\n<p>Sin embargo, choc\u00f3 su Volkswagen Polo R WRC en unas condiciones resbaladizas y traicioneras, entregando el liderato a Meeke por 4.8 segundos de ventaja sobre Neuville. Pero el piloto de Irlanda del Norte chocar\u00eda pronto contra un muro despu\u00e9s de un error en la toma de notas, arrancando la rueda trasera izquierda de su Citro\u00ebn DS3 WRC.<\/p>\n<p>Andreas Mikkelsen sobrevivi\u00f3 a un trompo en el lugar del accidente de Latvala para adjudicarse la tercera posici\u00f3n con su Polo R WRC, a 17.3 segundos de Sordo. Elfyn Evans destac\u00f3 en su debut en asfalto con un World Rally Car, igualando el mejor resultado de su carrera deportiva al finalizar en cuarta posici\u00f3n, 6.9 segundos por delante del Ford Fiesta RS pilotado por su experimentado compa\u00f1ero Mikko Hirvonen.<\/p>\n<p>A pesar de haber abandonado despu\u00e9s de dos accidentes, S\u00e9bastien Ogier mantiene 44 puntos de ventaja sobre Latvala en la general. Aunque el desgraciado fin de semana de ambos impidiera a su equipo sentenciar el t\u00edtulo de constructores, los resultados garantizan que un piloto de Volkswagen (Latvala, Ogier o Mikkelsen) se va a llevar esta temporada la corona de pilotos.<\/p>\n<p>Texto: Prensa WRC.COM<\/p>\n<div align=\"center\"><script src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- Scrip_google_300x250 --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 300px; height: 250px;\" data-ad-client=\"ca-pub-8210995772042445\" data-ad-slot=\"9319737050\"><\/ins><script>\/\/ <![CDATA[\n(adsbygoogle = window.adsbygoogle || []).push({});\n\/\/ ]]><\/script><\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Neuville consegu\u00eda en Alemania su primera victoria en el Campeonato del Mundo de Rallyes, tres d\u00edas despu\u00e9s de casi destruir su coche cuando dio seis vueltas de campana en el Shakedown.En la \u00faltima jornada, Neuville ha pasado de la tercera a la primera posici\u00f3n despu\u00e9s de los abandonos cuando eran l\u00edderes de Jari-Matti Latvala y [&hellip;]<!-- AddThis Advanced Settings generic via filter on wp_trim_excerpt --><!-- AddThis Share Buttons generic via filter on wp_trim_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[27],"tags":[],"class_list":["post-390","post","type-post","status-publish","format-standard","hentry","category-c46-rallyes-mundial"],"_links":{"self":[{"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/posts\/390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/comments?post=390"}],"version-history":[{"count":3,"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/posts\/390\/revisions"}],"predecessor-version":[{"id":588,"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/posts\/390\/revisions\/588"}],"wp:attachment":[{"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/media?parent=390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/categories?post=390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/tags?post=390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}