{"id":4044,"date":"2018-12-18T16:10:15","date_gmt":"2018-12-18T14:10:15","guid":{"rendered":"http:\/\/www.cantabriarallye.net\/newcantabriarallye\/?p=4044"},"modified":"2018-12-19T09:01:05","modified_gmt":"2018-12-19T07:01:05","slug":"berto-dertiano-vuelve-a-ganar-en-casa","status":"publish","type":"post","link":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/berto-dertiano-vuelve-a-ganar-en-casa\/","title":{"rendered":"Berto Dertiano, vuelve a ganar \u00aben casa\u00bb"},"content":{"rendered":"<p>Victoria de Berto Dertiano, con su Peugeot 205 Coll de Turini, que volv\u00eda a ganar en \u00abcasa\u00bb. La segunda posici\u00f3n con el mismo veh\u00edculo era para Javier G\u00f3mez, siendo Javi Aja el tercer clasificado con su \u00abCorsa GSI \u00bb del equipo \u00abRamiro Sport\u00bb.<br \/>La tracci\u00f3n trasera era para Domingo Estrada, con el BMW del equipo \u00abPi\u00f1a Sport\u00bb, siendo la segunda posici\u00f3n para Ra\u00fal L\u00f3pez Cagigal, con su Opel Kadett City.<br \/>Verdadero espect\u00e1culo, con un Slalom mixto, en donde la inscripci\u00f3n fue muy grande, adem\u00e1s de un lleno total de publico. GRAN TRABAJO de la escuder\u00eda Turbo y todos sus integrantes, que volv\u00edan a demostrar su buen hacer. Diego Vidal consegu\u00eda tambi\u00e9n el Campeonato de la especialidad.<\/p>\n<table align=\"center\" border=\"0\">\n<tbody>\n<tr>\n<td>\n<div align=\"center\">\n<p><img decoding=\"async\" src=\"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-content\/uploads\/2018\/slalom2018\/solares\/berto.jpg\"><\/p>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">\n<p><span style=\"font-family: Verdana, Arial, Helvetica, sans-serif;\">Berto Dertiano, volv\u00eda a ganar \u00aben casa\u00bb.<br \/>Foto :CantabriaRallye.net<\/span><\/p>\n<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><!--more--><\/p>\n<table align=\"right\" border=\"0\">\n<tbody>\n<tr>\n<td>\n<div align=\"center\">\n<p><img decoding=\"async\" src=\"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-content\/uploads\/2018\/slalom2018\/solares\/berto.jpg\"><\/p>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">\n<p><span style=\"font-family: Verdana, Arial, Helvetica, sans-serif;\">Berto Dertiano, volv\u00eda a ganar \u00aben casa\u00bb, siendo<br \/>Javier G\u00f3mez con el mismo veh\u00edculo, el<br \/>segundo clasificado.<br \/>Foto :CantabriaRallye.net<\/span><\/p>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">\n<p><img decoding=\"async\" src=\"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-content\/uploads\/2018\/slalom2018\/solares\/aja.jpg\"><\/p>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">\n<p><span style=\"font-family: Verdana, Arial, Helvetica, sans-serif;\">La tercera posici\u00f3n en Solares era para<br \/>Javi Aja y el equipo \u00abRamiro Sport\u00bb.<br \/>Foto :CantabriaRallye.net<\/span><\/p>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">\n<p><img decoding=\"async\" src=\"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-content\/uploads\/2018\/slalom2018\/solares\/diego.jpg\"><\/p>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">\n<p><span style=\"font-family: Verdana, Arial, Helvetica, sans-serif;\">Diego Vidal era el cuarto clasificado y<br \/>consegu\u00eda TAMBI\u00c9N el Campeonato de<br \/>Cantabria de la especialidad.<br \/>Foto :CantabriaRallye.net<\/span><\/p>\n<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Otra nueva edici\u00f3n del Slalom de solares y OTRA nueva victoria para Berto Dertiano. El piloto del equipo Coll de Turini, consegu\u00eda un \u00abdoblete\u00bb al imponerse tambi\u00e9n en la pasada temporada.<br \/>Tambi\u00e9n, esta ultima prueba del a\u00f1o, decid\u00eda al Campe\u00f3n de la modalidad de Slalom, siendo este Diego Vidal, que con su Mini 1000conseguia el campeonato.<br \/>Excelente trabajo de toda la escuder\u00eda Turbo, para sacar la prueba adelante y que finalmente volv\u00eda a ser un verdadero \u00e9xito de participaci\u00f3n y de publico en general.<br \/>Tambi\u00e9n decir que es el \u00fanico Slalom Mixto y dicho sea &#8230;de paso, es lo que gusta a los participantes.<\/p>\n<p>Finalmente eran 65 los inscritos a este Slalom de Navidad, estando entre ellos, el copiloto MUNDIALES Carlos del Barrio, que no quer\u00eda perderse esta prueba.<\/p>\n<p>Excelente ambiente, mucho publico, gran inscripci\u00f3n y en general de TODO para la ultima prueba de la temporada de motor en Cantabria.<br \/>Despu\u00e9s de los \u00e9ntrenos llegaban las mangas oficiales, celebr\u00e1ndose tan solo Dos de ellas, pues el alto numero de participantes, hacia inviable las tres mangas oficiales.<\/p>\n<p>Despu\u00e9s de la manga de \u00e9ntrenos comenzaba la prueba propiamente dicha, siendo el mejor de los registros para Berto Dertiano, que volv\u00eda a \u00absacar\u00bb una vez mas, su \u00abPeugeot\u00bb, demostrando su buena forma f\u00edsica y tambi\u00e9n la de su Peugeot. Dertiano volv\u00eda a conseguir el mejor registro, siendo este de 1:28,09. Dertiano comenzaba fuerte y en la prueba \u00abde casa\u00bb no hay quien le \u00abtosa\u00bb.<br \/>Por detr\u00e1s ten\u00edamos a Javi Aja. El joven piloto con su modesto Opel Corsa, rodaba perfectamente en la tierra, si bien las nuevas cubiertas de tierra, hac\u00edan su trabajo. Aja consegu\u00eda el MISMO crono que Dertiano, tan solo diferenciado por unas cent\u00e9simas de segundo. El equipo \u00abRamiro Sport\u00bb, preparador oficial del piloto del piloto de Cece\u00f1as, realiza un estupendo trabajo.<\/p>\n<p>El tercer clasificado era Javier G\u00f3mez, con el mismo coche que Dertiano. G\u00f3mez consegu\u00eda colocarse a tan solo UN segundo del actual l\u00edder, que no era otro que su compa\u00f1ero de equipo.<\/p>\n<p>La cuarta posici\u00f3n era para Diego Vidal con su Mini 1000, con el MISMO crono que Javi G\u00f3mez, diferenciado tan solo por unas cent\u00e9simas de segundo.<br \/>El quinto clasificado era Roberto L\u00f3pez, con su habitual Peugeot 205. L\u00f3pez en esta ocasi\u00f3n no pod\u00eda optar al campeonato, pero sus OCHO CAMPEONATOS consecutivos, dicen mucho del piloto de La Cavada. Roberto consegu\u00eda un crono de 1:30,54.<\/p>\n<p>En tracci\u00f3n trasera el mejor de los cronos en esta primera manga era para Ra\u00fal L\u00f3pez Cigala. El menor de la familia L\u00f3pez Cagigal, consegu\u00eda la victoria en esta manga, rodando muy r\u00e1pido con su Opel Kadett City.<br \/>La segunda posici\u00f3n era para su hermano Juan Ma L\u00f3pez Cagigal, que corr\u00eda con \u00abotro\u00bb de sus Opel Manta, siendo la tercera posici\u00f3n para Fernando Prada.<br \/>Espectacular la carrera que se estaba disputando en Solares.<\/p>\n<p><!--nextpage--><\/p>\n<table align=\"right\" border=\"0\">\n<tbody>\n<tr>\n<td>\n<div align=\"center\">\n<p><img decoding=\"async\" src=\"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-content\/uploads\/2018\/slalom2018\/solares\/estrada.jpg\"><\/p>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">\n<p><span style=\"font-family: Verdana, Arial, Helvetica, sans-serif;\">La tracci\u00f3n trasera era para Domingo Estrada,<br \/>con el BMW del equipo \u00abPi\u00f1a Sport\u00bb.<br \/>Foto :CantabriaRallye.net<\/span><\/p>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">\n<p><img decoding=\"async\" src=\"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-content\/uploads\/2018\/slalom2018\/solares\/raul.jpg\"><\/p>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">\n<p><span style=\"font-family: Verdana, Arial, Helvetica, sans-serif;\">La segunda posici\u00f3n era para Ra\u00fal L\u00f3pez con<br \/>el Opel Kadett city.<br \/>Foto :CantabriaRallye.net<\/span><\/p>\n<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Comenzaba la segunda manga ocficial. En esta segunda manga Dertiano volv\u00eda a conseguir la victoria. El piloto del Equipo Coll de Turini, esta especializado en ganar en la prueba \u00abde casa\u00bb. (lleva dos a\u00f1os haci\u00e9ndolo y solo compite en esta prueba).<br \/>Dertiano consegu\u00eda un crono de 1:26,76, con lo que se pon\u00eda LIDER tambi\u00e9n en esta segunda manga.<br \/>La segunda posici\u00f3n era para Javier G\u00f3mez con el mismo coche. Javi, consegu\u00eda colocarse por detr\u00e1s a tan solo UN segundo.<br \/>La tercera posici\u00f3n en esta segunda manga oficial, era para Cesar Canales. Canales con su Peugeot 206 GTI, realizaba una manga espectacular, con un su peque\u00f1o Peugeot 206. 1:30,25 era el crono de Canales.<br \/>La cuarta posici\u00f3n en esta pasada era para Javi Aja, que en Solares quer\u00eda hacerlo bien. Otro de los pilotos Cantabria Rallye, ya nos confirmaba a lo largo de la semana su intenci\u00f3n de rodar mejor que bien y finalmente los estaba consiguiendo, con su peque\u00f1o \u00abcorseta\u00bb. ESPECTACULAR Javi Aja. 1:31,64 era el crono de Aja.<br \/>Finalmente la quinta posici\u00f3n era para Borja Gonz\u00e1lez, que con su \u00abotro\u00bb coche de tierra, tambi\u00e9n estaba rodando muy bien. Gonz\u00e1lez consegu\u00eda un crono de 1:33,03.<\/p>\n<p>La tracci\u00f3n trasera en esta segunda manga era para Domingo Estrada con el BMW. El benjam\u00edn de la familia Estrada, estaba rodando muy bien, consiguiendo unos cronos mas que destacables. No tenemos que olvidarnos, que en la pasada temporada y en esta misma prueba, con el coche de su padre, Mingo en su primera participaci\u00f3n, sorprend\u00eda a todos, con sus cronos.<br \/>La segunda posici\u00f3n en tracci\u00f3n trasera era para Ra\u00fal L\u00f3pez Cagigal, con su Opel Kadett City.<br \/>Decir, que la tercera manga era anulada, pues se \u00abechaba\u00bb la noche encima.<br \/>Finalmente con los cronos en la mano y prevaleciendo el mejor de las mangas oficiales, el mejor de los cronos y vencedor del Slalom, era Berto Dertiano, con su Peugeot 205 Coll de Turini.<br \/>La segunda posici\u00f3n era para Javier G\u00f3mez, que compart\u00eda coche con Dertiano y una vez que \u00abcog\u00eda el hilo a esto\u00bb, consegu\u00eda colocarse por detr\u00e1s de Dertiano.<br \/>El tercer clasificado era Javi Aja. El piloto del Corsa, realizaba la mejor actuaci\u00f3n de la temporada. Los \u00faltimos retoques de \u00abRamiro Sport\u00bb, consegu\u00edan su objetivo.<\/p>\n<p>En tracci\u00f3n trasera el l\u00edder era Domingo Estrada, que con la gran actuaci\u00f3n de la segunda manga, consegu\u00eda colocarse l\u00edder de la especialidad. Otro piloto que dar\u00e1 que hablar, por su Juventud y por las ganas de hacer las cosas bien.<br \/>El segundo clasificado era Ra\u00fal L\u00f3pez con el Opel Kadett City, de la familia L\u00f3pez Cagigal.<br \/>Los Car-Cross fueron verdadera legi\u00f3n en Solares, siendo el mejor de ellos Kevin Garc\u00eda, que \u00abganaba\u00bb el Slalom, por tiempos aunque no puntuasen, para la clasificaci\u00f3n oficial. Decir que los Car-Cross estaban en su \u00abterreno.<br \/>Jos\u00e9 Carlos Ortiz e Ivan P\u00e9rez eran quienes le segu\u00edan, entre los car-cross.<\/p>\n<p>Despu\u00e9s la entrega de premios en el Balneario de Solares, pon\u00eda el punto y final a este magnifico Slalom de Navidad, otro GRAN \u00e9xito de la nueva escuder\u00eda Turbo. Una vez mas, se demuestra que con trabajo se puede hacer de todo. Ya nos lo han demostrado los integrantes de la escuder\u00eda Turbo, que a ellos el trabajo no les asusta.<br \/>Finalmente en la entrega de premios, se le entregaba una placa conmemorativa a Carlos del Barrio, copiloto MUNDIALISTA y que ha estado disfrutando con todos nosotros, como otro piloto m\u00e1s. Excelente copiloto y MEJOR PERSONA, que ha prometido volver al Slalom de Solares.<\/p>\n<table align=\"center\" border=\"0\" width=\"294\">\n<tbody>\n<tr>\n<td>\n<div align=\"center\">\n<p><span style=\"font-size: x-large;\"><b>!!! LA FOTO \u00a1\u00a1\u00a1<\/b><\/span><\/p>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">\n<p><img decoding=\"async\" src=\"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-content\/uploads\/2018\/slalom2018\/solares\/foto1.jpg\"><\/p>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p align=\"center\"><span style=\"font-family: Verdana, Arial, Helvetica, sans-serif;\">Carlos Del Barrio, que participo en el Slalom con un Kart<br \/>Croos, posando junto a Dani Sordo y Carlos Ortiz.<br \/>VERDADEROS CAMPEONES, apoyando la prueba de<br \/>Solares.<br \/>Foto :CantabriaRallye.net<\/span><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table align=\"center\" border=\"0\" width=\"294\">\n<tbody>\n<tr>\n<td>\n<div align=\"center\">\n<p><span style=\"font-size: x-large;\"><b>!!! LA FOTO 2\u00a1\u00a1\u00a1<\/b><\/span><\/p>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">\n<p><img decoding=\"async\" src=\"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-content\/uploads\/2018\/slalom2018\/solares\/foto2.jpg\"><\/p>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">\n<p><span style=\"font-family: Verdana, Arial, Helvetica, sans-serif;\">En la entrega de trofeos, la escudar\u00eda Turbo, entregaba<br \/>a Carlos del Barrio una placa en conmemoraci\u00f3n.<br \/>Foto :CantabriaRallye.net<\/span><\/p>\n<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Victoria de Berto Dertiano, con su Peugeot 205 Coll de Turini, que volv\u00eda a ganar en \u00abcasa\u00bb. La segunda posici\u00f3n con el mismo veh\u00edculo era para Javier G\u00f3mez, siendo Javi Aja el tercer clasificado con su \u00abCorsa GSI \u00bb del equipo \u00abRamiro Sport\u00bb.La tracci\u00f3n trasera era para Domingo Estrada, con el BMW del equipo \u00abPi\u00f1a [&hellip;]<!-- AddThis Advanced Settings generic via filter on wp_trim_excerpt --><!-- AddThis Share Buttons generic via filter on wp_trim_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-4044","post","type-post","status-publish","format-standard","hentry","category-c3-slalom"],"_links":{"self":[{"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/posts\/4044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/comments?post=4044"}],"version-history":[{"count":2,"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/posts\/4044\/revisions"}],"predecessor-version":[{"id":4047,"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/posts\/4044\/revisions\/4047"}],"wp:attachment":[{"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/media?parent=4044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/categories?post=4044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cantabriarallye.net\/newcantabriarallye\/wp-json\/wp\/v2\/tags?post=4044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}